{"id":32,"date":"2023-01-10T16:21:04","date_gmt":"2023-01-10T21:21:04","guid":{"rendered":"https:\/\/revues.dev.uqam.ca\/iref\/?page_id=32"},"modified":"2024-08-14T21:21:36","modified_gmt":"2024-08-14T21:21:36","slug":"archives","status":"publish","type":"page","link":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros-revue\/archives\/","title":{"rendered":"Archives"},"content":{"rendered":"<div class=\"custom-tax-archive container\"><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-24-no-1-marges-et-intersections\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/07\/couvertureVF-scaled.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-24-no-1-marges-et-intersections\/\">Vol. 24 no. 1 \u2013 \u00ab Marges et intersections \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/agin-blais-maude\/'>Maude Agin-Blais<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/lea-delambre\/'>L\u00e9a Delambre<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/dube-noemie\/'>No\u00e9mie Dub\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/merlet-em\/'>Em Merlet<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/pascale-monnette\/'>Pascale Monnette<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/genevieve-proulx-masson\/'>Genevi\u00e8ve Proulx-Masson<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/flora-roussel\/'>Flora Roussel<\/a><\/div><\/section><p>Les marges ont souvent \u00e9t\u00e9 appr\u00e9hend\u00e9es \u2013 et \u00e0 juste titre \u2013 en termes d\u2019exclusion et d\u2019invisibilisation ou, au contraire, de surveillance accrue (Crosby &amp; Monaghan, 2018; Maynard, 2017). Cette surveillance marque les rapports que les marges entretiennent avec le centre \u2013 lieu tr\u00e8s souvent soustrait \u00e0 l\u2019examen critique (Haraway, 2007 [1988]) et \u00e0 l\u2019int\u00e9rieur duquel se concentrent pouvoir, ressources et privil\u00e8ges. Bien que travers\u00e9es par les violences, les marges m\u00e9ritent pourtant d\u2019\u00eatre c\u00e9l\u00e9br\u00e9es dans toute leur vitalit\u00e9, leur dynamisme et leur conflictualit\u00e9. Par d\u00e9finition mouvantes, elles s\u2019offrent comme lieux de rencontres par excellence, stimulant la recherche de nouvelles mani\u00e8res de faire, d\u2019\u00eatre, de dire et de percevoir ensemble. Or, si c\u2019est souvent des marges que les dialogues et solidarit\u00e9s \u00e9mergent, ces espaces ne sont en aucun cas exempts des rapports de domination et d\u2019exploitation qui structurent nos soci\u00e9t\u00e9s. Face aux \u00e9cueils de la culpabilit\u00e9 et du d\u00e9sespoir, pouvons-nous plut\u00f4t revendiquer les potentialit\u00e9s transformatrices et, \u00e9ventuellement, gu\u00e9risseuses, de la responsabilit\u00e9 et de l\u2019inconfort (Boler, 1999)?<br>\r\n<\/br>\r\nSe pr\u00e9sentant tant\u00f4t sous forme d\u2019exercices acad\u00e9miques, tant\u00f4t sous forme de t\u00e9moignages et de cr\u00e9ations, les pens\u00e9es et exp\u00e9riences pr\u00e9sent\u00e9es dans les contributions qui composent <em>Marges &amp; Intersections<\/em> esquissent trois grandes trajectoires d\u2019exploration de cette question. La premi\u00e8re interroge les enjeux de repr\u00e9sentation et de reconnaissance des injustices et violences (physiques, \u00e9motionnelles, \u00e9pist\u00e9mologiques\u2026) telles que v\u00e9cues \u00e0 diff\u00e9rentes intersections. De son c\u00f4t\u00e9, la seconde trajectoire regroupe des textes consacr\u00e9s aux potentialit\u00e9s de subversion et d\u2019<em>empowerment<\/em> en germe dans l\u2019acte de se r\u00e9approprier des identit\u00e9s et perspectives activement d\u00e9valoris\u00e9es, voire effac\u00e9es par les normes et institutions dominantes. Finalement, la troisi\u00e8me trajectoire explore comment diff\u00e9rentes perspectives, pertinences et champs de r\u00e9flexion issus de diverses positionnalit\u00e9s peuvent se rejoindre pour cr\u00e9er des opportunit\u00e9s de solidarit\u00e9 et d\u2019innovation.<br>\r\n<\/br>\r\n\r\n\u2014\u2014\u2014<br>\r\n<\/br>\r\n\r\nLe num\u00e9ro 24 sera disponible en ligne sous peu, d\u00e8s que le num\u00e9ro 25 aura \u00e9t\u00e9 lanc\u00e9. En attendant, vous pouvez vous le procurer en format papier \u00e0 la librairie l'<a title=\"Eugu\u00e9lionne\" href=\"https:\/\/librairieleuguelionne.com\/\">Eugu\u00e9lionne<\/a>, au <a title=\"Port-de-t\u00eate\" href=\"https:\/\/www.leportdetete.com\/\">Port-de-t\u00eate<\/a>, \u00e0 la <a title=\"Coop de l\u2019UQAM\" href=\"https:\/\/www.coopuqam.com\/\">Coop de l\u2019UQAM<\/a>, ainsi qu\u2019en entrant directement en contact avec nous!<br>\r\n<\/br>\r\n\r\n<b><strong>ISSN : 1911-4176<\/strong><\/b><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-23-no-1-futurs-et-projections\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/07\/Vol.-23_Cover-1.jpg\" alt=\"http:\/\/Couverture%20de%20la%20revue%202020\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-23-no-1-futurs-et-projections\/\">Vol. 23 no. 1 \u2013 \u00ab Futurs et projections \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/agin-blais-maude\/'>Maude Agin-Blais<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/dube-noemie\/'>No\u00e9mie Dub\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/giroux-alexia\/'>Alexia Giroux<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/merlet-em\/'>Em Merlet<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/ouedraogo-paola\/'>Paola Ouedraogo<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/parenteau-labarre-carolane\/'>Carolane Parenteau-Labarre<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/rinfret-viger-sabrina\/'>Sabrina Rinfret-Viger<\/a><\/div><\/section><p>Date de publication : 18 novembre 2020<br \/>\r\n<br \/>\r\n\u00c0 l\u2019aube d\u2019une nouvelle d\u00e9cennie et au cr\u00e9puscule du premier quart de si\u00e8cle de F\u00e9min\u00c9tudes, en pleine crise climatique et \u2013 donn\u00e9e nouvelle \u2013 sanitaire, le th\u00e8me de ce num\u00e9ro s\u2019est presque impos\u00e9 de lui-m\u00eame. Co\u00efncidant \u00e9galement avec les 30 ans de l\u2019Institut de recherches et d\u2019\u00e9tudes f\u00e9ministes (IREF), ce moment charni\u00e8re nous a sembl\u00e9 synonyme de transitions et de tensions entre ce qu\u2019ont \u00e9t\u00e9, ce que sont et ce que deviendront les f\u00e9minismes. Alors que le pass\u00e9 est remis en question et que le pr\u00e9sent est plus incertain que jamais, dans quelle direction pouvons-nous nous tourner sinon vers l\u2019avant? <br \/>\r\n<br \/>\r\nAu c\u0153ur de ce num\u00e9ro figurent des questions li\u00e9es \u00e0 l\u2019inclusion, \u00e0 l\u2019intersectionnalit\u00e9, au d\u00e9passement des binarismes, \u00e0 l\u2019environnement naturel ou b\u00e2ti, \u00e0 la repr\u00e9sentation sociale et \u00e0 la solidarit\u00e9. Une pluralit\u00e9 de sujets y sont abord\u00e9s \u00e0 travers une pluralit\u00e9 de formes et de perspectives, notamment le t\u00e9moignage, la communication publique, les \u00e9tudes critiques du handicap, l\u2019histoire, les \u00e9tudes urbaines, les sciences cognitives, l\u2019art visuel, les \u00e9tudes litt\u00e9raires et l\u2019\u00e9criture cr\u00e9ative. Ces deux derni\u00e8res caract\u00e9risent d\u2019ailleurs la moiti\u00e9 des textes et \u0153uvres ici rassembl\u00e9es, signalant le pouvoir, les potentialit\u00e9s de la litt\u00e9rature qui permet d\u2019imaginer \u00e0 quoi pourrait ressembler un monde f\u00e9ministe. Il convient aussi de souligner que l\u2019urgence des changements climatiques se fait sentir derri\u00e8re plusieurs des contributions, et ce sans que nous l\u2019ayons nous-m\u00eames incluse dans l\u2019appel initial; l\u2019actualit\u00e9 l\u2019a fait pour nous.<br \/>\r\n<br \/>\r\nL\u2019intitul\u00e9 <em>Luttes f\u00e9ministes\u00a0: futurs et projections<\/em> nous est apparu \u00e0 l\u2019automne 2019 dans la volont\u00e9 de repenser l\u2019\u00e0-venir de ce mouvement social. Les contributions re\u00e7ues et choisies s\u2019articulent en trois temps : une r\u00e9trospective des luttes ant\u00e9rieures, d\u2019abord; un \u00e9tat des lieux des enjeux contemporains, ensuite; un regard vers l\u2019\u00ab apr\u00e8s \u00bb, enfin.<br \/>\r\n<br \/>\r\n<strong>ISSN : 1911-4176<\/strong><br \/>\r\n<br \/><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/02\/Vol.-23_Complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/guide-decriture-inclusive\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/02\/Couverture-guide.png\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 septembre 2020<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/guide-decriture-inclusive\/\">Guide d&#039;\u00e9criture inclusive<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/agin-blais-maude\/'>Maude Agin-Blais<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marion-gingras-gagne\/'>Marion Gingras-Gagn\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/giroux-alexia\/'>Alexia Giroux<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/sophie-guinamand\/'>Sophie Guinamand<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/merlet-em\/'>Em Merlet<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/parenteau-labarre-carolane\/'>Carolane Parenteau-Labarre<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/rinfret-viger-sabrina\/'>Sabrina Rinfret-Viger<\/a><\/div><\/section><p>Num\u00e9ro hors-s\u00e9rie. <br>\r\n<\/br>\r\nCe guide de r\u00e9daction inclusive cherche \u00e0 offrir des pistes de solution efficaces pour pratiquer une \u00e9criture f\u00e9ministe, queer et antioppressive, afin de transformer la langue pour qu\u2019elle soit plus repr\u00e9sentative de toustes.<br>\r\n<\/br>Il a \u00e9t\u00e9 r\u00e9dig\u00e9 par des personnes queer, non-binaires et cis-alli\u00e9es.<br>\r\n<\/br><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/02\/FEMINETUDES_Guide-ecriture_page-par-page.pdf\">Pour t\u00e9l\u00e9charger le guide complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-22-no-1-corps-et-resistances\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/07\/22_couverture.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 23 mars 2019<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-22-no-1-corps-et-resistances\/\">Vol. 22 no. 1 - \u00ab\u00a0Corps et r\u00e9sistances \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/audrey-deveault\/'>Audrey Deveault<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/dube-noemie\/'>No\u00e9mie Dub\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/laura-gagnon\/'>Laura Gagnon<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/amelie-langlois\/'>Am\u00e9lie Langlois<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/pascale-laplante-dube\/'>Pascale Laplante-Dub\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/levasseur-julie\/'>Julie Levasseur<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/nymphea-lopez\/'>Nymph\u00e9a Lopez<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/gabrielle-menard\/'>Gabrielle M\u00e9nard<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/lilah-mercader-duplain\/'>Lilah Mercader Duplain<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/sarah-turner\/'>Sarah Turner<\/a><\/div><\/section><p>Pourquoi encore le corps? Question simple, en apparence, mais qui impose des nuances, convoque la multiplicit\u00e9 des individualit\u00e9s. Quantit\u00e9 de voix s\u2019\u00e9l\u00e8vent, parlent, demandent, \u00e9changent dans une cacophonie cr\u00e9atrice. Des paroles, des corps\u2026 encore.<br \/>\r\n<br \/>\r\nEncore le corps, parce qu\u2019il s\u2019est immisc\u00e9 subtilement, d\u00e8s notre premi\u00e8re rencontre. Parce qu\u2019il s\u2019est incrust\u00e9 dans toutes nos propositions, parce qu\u2019il revenait sous diverses formes, par des chemins d\u00e9tourn\u00e9s. Autant de fils qui, aussi \u00e9tonnant que cela puisse para\u00eetre, finissaient toujours par nous ramener \u00e0 ce noeud, \u00e0 cette th\u00e9matique cl\u00e9 qui en lie tant d\u2019autres. Quelque temps avant la mont\u00e9e des mouvements que l\u2019on conna\u00eet maintenant bien, quelque temps avant la popularisation de #MeToo, avant #BalanceTonPorc, nous sentions d\u00e9j\u00e0 l\u2019importance de ce th\u00e8me in\u00e9vitable, qui avait \u00e9merg\u00e9 spontan\u00e9ment aux croisements de nos discussions. Il r\u00e9sonnait en nous, nourrissait les d\u00e9bats, exposait les tensions. Un sujet qui semble donc arriver \u00e0 point nomm\u00e9 dans le climat social actuel, mais qui aura tout de m\u00eame n\u00e9cessit\u00e9 beaucoup de r\u00e9flexion et aura longuement m\u00fbri tout au long du processus \u00e9ditorial.<br \/>\r\n<br \/>\r\nParce que le corps, nous l\u2019avions sur le coeur. Nous en avions assez d\u2019en parler, assez de sa spectacularisation, assez d\u2019avoir l\u2019impression d\u2019y \u00eatre r\u00e9duit.e.s\u2026 Mais, n\u2019\u00e9tait-il pas aussi au centre d\u2019\u00e0 peu pr\u00e8s toutes les revendications f\u00e9ministes? Il se r\u00e9v\u00e9lait le lieu d\u2019un grand paradoxe, un terreau fertile pour le d\u00e9veloppement d\u2019une r\u00e9flexion tenant compte de ses multiples facettes. C\u2019est pourquoi, en choisissant d\u2019intituler ce num\u00e9ro \u00ab Corps &amp; R\u00e9sistances \u00bb, nous souhaitions offrir un espace qui permettrait la r\u00e9appropriation de non pas un seul corps - ce corps id\u00e9alis\u00e9 de la Femme avec un grand F - mais bien de plusieurs corps, et ce, en nos propres termes. Nous cherchions \u00e0 cr\u00e9er un endroit pour entendre les diff\u00e9rentes perspectives, pour ouvrir le dialogue, pour \u00e9prouver les nombreux points de contact. Un espace s\u00e9curitaire qui rendrait \u00e0 la fois possible la c\u00e9l\u00e9bration des r\u00e9sistances, mais aussi la d\u00e9nonciation de l\u2019objectification parfois subtile, parfois explicite et tr\u00e8s souvent violente, de ces corps uniques et diversifi\u00e9s.<br \/>\r\n<br \/>\r\nUn th\u00e8me multiple, un th\u00e8me solidaire, donc, qui permet autant la r\u00e9sistance individuelle que collective. Mais aussi un th\u00e8me paradoxal, dichotomique, qui vise \u00e0 explorer les tensions inh\u00e9rentes au fait d\u2019\u00eatre sujet r\u00e9sistant au discours objectivant, d\u2019\u00eatre corps social parmi d\u2019autres corps sociaux, d\u2019\u00eatre individualit\u00e9 dans la multitude. Car c\u2019est \u00e0 travers ce v\u00e9hicule de notre identit\u00e9, c\u2019est \u00e0 travers cet interface qu\u2019il nous est possible d\u2019entrer en dialogue, de transmettre notre pens\u00e9e. C\u2019est en lan\u00e7ant le fil de notre voix que chacun.e d\u2019entre nous est en mesure de toucher ce noeud dont nous faisons tou.te.s partie afin de tenter d\u2019en d\u00e9m\u00ealer les innombrables composantes.<br \/>\r\n<br \/>\r\n<strong>ISSN : 1911-4176<\/strong><br \/>\r\n<br \/>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/02\/Vol.-22_Complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><br \/>\r\n<br \/>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/02\/Vol.-22-Zine.pdf\">Pour t\u00e9l\u00e9charger le zine accompagnant le num\u00e9ro en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-21-no-1-postures-et-privileges\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/08\/coverfeminetudes-au-complet_page-0001.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 6 f\u00e9vrier 2017<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-21-no-1-postures-et-privileges\/\">Vol. 21 no. 1 - \u00ab Postures et privil\u00e8ges \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/raphaelle-ainsley-vincent\/'>Rapha\u00eblle Ainsley-Vincent<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/charlotte-biddle-bocan\/'>Charlotte Biddle Bocan<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/anne-marie-boutin-lagace\/'>Anne-Marie Boutin-Lagac\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/mahelie-caschetto-l\/'>Mah\u00e9lie Caschetto-L.<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/katherine-chartrand-pelletier\/'>Katherine Chartrand-Pelletier<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/laura-gagnon\/'>Laura Gagnon<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/alexandra-houle\/'>Alexandra Houle<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/valerie-rioux\/'>Val\u00e9rie Rioux<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/catherine-rousseau\/'>Catherine Rousseau<\/a><\/div><\/section><p>Postures et privil\u00e8ges, voil\u00e0 un th\u00e8me qui s\u2019impose.\r\nParce que les oppressions sont multiples; parce que les f\u00e9minismes sont pluriels. Parce que les luttes tirent pr\u00e9cis\u00e9ment leur force et leur vitalit\u00e9 de cette diversit\u00e9 d\u2019exp\u00e9riences, de points de vue et de positionnements th\u00e9oriques dans lesquels chaque f\u00e9ministe se construit. Et parce qu\u2019en \u00e9tant plurielles, on peut \u00eatre alli\u00e9.e.s et solidaires, veut-on esp\u00e9rer. <br \/>\r\n<br \/>\r\nChoisir ce th\u00e8me, c\u2019\u00e9tait la volont\u00e9 d\u2019amener F\u00e9min\u00c9tudes \u00e0 la rencontre des POSTURES, mais surtout de l\u2019ouvrir \u00e0 la probl\u00e9matisation des PRIVIL\u00c8GES. Et d\u2019abord ceux de la revue. Ce fut une introspection et une prise de conscience; d\u2019o\u00f9 parle-t-on, quels mots utilise-t-on, en quels lieux publie-t-on, et pour qui ? Le but n\u2019\u00e9tant pas d\u2019apporter des r\u00e9ponses, mais justement de continuellement se remettre en question; \u00eatre dans un constant processus de r\u00e9flexion. Nous pensions ainsi nous assurer une posture \u00ab consciente et coh\u00e9rente \u00bb. Cependant, chemin faisant, nous constations une tension entre un id\u00e9al \u00ab conscient et coh\u00e9rent \u00bb et notre capacit\u00e9 \u00e0 produire de telles actions. Sans compter la diversit\u00e9 de ce qui est entendu par \u00ab conscientes et coh\u00e9rentes \u00bb au sein d\u2019un m\u00eame comit\u00e9 (groupe) ...<br \/>\r\n<br \/>\r\n\u00c9tant une revue autog\u00e9r\u00e9e, F\u00e9min\u00e9tudes a donc eu la libert\u00e9 d\u2019\u00e9voluer au gr\u00e9 de ces questionnements qui se refl\u00e8tent organiquement jusque dans le nouveau format de ce 21e num\u00e9ro. Nous avions le d\u00e9sir d\u2019am\u00e9nager un espace d'\u00e9change, de faire \u00e9merger un lieu de rencontre, qui puisse cultiver une pluralit\u00e9 de f\u00e9minismes. Ces pages accueillent d\u00e8s lors des paroles f\u00e9ministes de tous genres, des paroles alli\u00e9es; des savoirs divers qui s\u2019expriment en voies multiples. Des prises de parole qui donnent\/red\u00e9finissent pouvoir.<br \/>\r\n<br \/>\r\n<strong>ISSN : 1911-4176<\/strong><br \/>\r\n<br \/><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/02\/Vol.-21-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-20-no-1-heritages-feministes\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/20_couverture.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 4 novembre 2015<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-20-no-1-heritages-feministes\/\">Vol. 20 no. 1 - \u00ab\u00a0H\u00e9ritages f\u00e9ministes : tensions et parall\u00e8les \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/raphaelle-ainsley-vincent\/'>Rapha\u00eblle Ainsley-Vincent<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/andreanne-beliveau-cote\/'>Andr\u00e9anne B\u00e9liveau-C\u00f4t\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/jade-bergeron\/'>Jade Bergeron<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/sandrine-bourget-lapointe\/'>Sandrine Bourget-Lapointe<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/gabrielle-dore\/'>Gabrielle Dor\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/guillaume-girard\/'>Guillaume Girard<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/claudine-paille\/'>Claudine Paill\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/camille-simard\/'>Camille Simard<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/julie-silveira\/'>Julie Silveira<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/catherine-sylvestre\/'>Catherine Sylvestre<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/camille-toffoli\/'>Camille Toffoli<\/a><\/div><\/section><p>En 1995, cinq ans apr\u00e8s la cr\u00e9ation de l\u2019Institut de recherches et d\u2019\u00e9tudes f\u00e9ministes (IREF), Audrey C\u00f4t\u00e9 et Sylvie Lamarre fondaient la revue F\u00e9min\u00c9tudes, avec le d\u00e9sir de cr\u00e9er un espace de r\u00e9flexion et de d\u00e9bat au sein du milieu f\u00e9ministe de l\u2019UQAM. L\u2019\u00e9ditorial de ce premier num\u00e9ro avait pour titre : \u00ab \u00catre f\u00e9ministe en 1995, est-ce n\u00e9cessaire ? \u00bb. La th\u00e9matique de la revue, l\u2019antif\u00e9minisme, rendait compte du climat d\u00e9favorable au f\u00e9minisme. L\u2019avenir de la revue n\u2019\u00e9tait donc pas assur\u00e9, malgr\u00e9 toute la bonne volont\u00e9 des fondatrices. Cependant, vingt ans plus tard, F\u00e9min\u00c9tudes re\u00e7oit une trentaine de propositions de textes et d\u2019oeuvres pour son vingti\u00e8me volume et son comit\u00e9 de r\u00e9daction compte alors plus de dix membres. La r\u00e9ponse \u00e0 la question pos\u00e9e dans le premier \u00e9ditorial semble d\u00e9sormais aller de soi : \u00eatre f\u00e9ministe en 2015, oui et plus que jamais ! <br \/>\r\n<br \/>\r\n\r\nLors de la cr\u00e9ation du 20e num\u00e9ro de F\u00e9min\u00c9tudes, l\u2019intention \u00e9tait de cr\u00e9er des liens avec nos pr\u00e9d\u00e9cesseures, de poursuivre ce qui avait \u00e9t\u00e9 commenc\u00e9. Ainsi, la question de l\u2019h\u00e9ritage s\u2019est impos\u00e9e d\u2019elle-m\u00eame. Nous voulions nous engager dans un exercice d\u2019autor\u00e9flexion en interrogeant les continuit\u00e9s et discontinuit\u00e9s, les cycles et les tensions qui caract\u00e9risent ces deux derni\u00e8res d\u00e9cennies de luttes et d\u2019\u00e9tudes f\u00e9ministes. Les textes du num\u00e9ro s\u2019inscrivent sous le signe de l\u2019h\u00e9ritage en ce qu\u2019ils traitent de sujets discut\u00e9s depuis les d\u00e9buts de la revue. Toutefois, les perspectives sur ces questions sont tout \u00e0 fait contemporaines.<br \/>\r\n<br \/>\r\n\r\nAfin de rendre hommage au travail des anciens comit\u00e9s de F\u00e9min\u00c9tudes, nous avons choisi d\u2019intituler chacune des sections de la revue par le titre d\u2019un ancien num\u00e9ro. Ainsi, nous cr\u00e9ons ce num\u00e9ro \u00e0 partir des archives de F\u00e9min\u00c9tudes pour cr\u00e9er une filiation visible et pour que son historique soit transmis.<br \/>\r\n<br \/>\r\n\r\n<strong>ISSN 1911-4176<\/strong><br \/>\r\n<br \/>\r\n\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Vol.-20-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-19-no-1-feminisme-au-quotidien\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Couverture-19.png\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 29 octobre 2014<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-19-no-1-feminisme-au-quotidien\/\">Vol. 19 no.1 - \u00ab\u00a0Le f\u00e9minisme au quotidien \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/corinne-arseneault\/'>Corinne Arseneault<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/sandrine-bourget-lapointe\/'>Sandrine Bourget-Lapointe<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/guillaume-girard\/'>Guillaume Girard<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/camille-simard\/'>Camille Simard<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/camille-toffoli\/'>Camille Toffoli<\/a><\/div><\/section><p>La th\u00e9matique du \u00ab f\u00e9minisme au quotidien \u00bb s\u2019est impos\u00e9e d\u2019elle-m\u00eame. Cela nous est apparu comme une mani\u00e8re de r\u00e9affirmer notre sensibilit\u00e9 f\u00e9ministe et notre appartenance au mouvement. Une mani\u00e8re de r\u00e9it\u00e9rer, comme plusieurs avant nous, que notre vie priv\u00e9e et quotidienne est tout aussi politique que nos implications au sein d\u2019organisations ou de groupes. Notre mode de vie et nos d\u00e9cisions de tous les jours sont teint\u00e9s par nos all\u00e9geances id\u00e9ologiques et nos valeurs ; dans la rue, au travail et \u00e0 l\u2019\u00e9cole, nous sommes toujours et encore f\u00e9ministes. Nous r\u00e9sistons tous les jours \u00e0 la culture patriarcale par des actions et des paroles simples. Que ce soit en refusant de sourire ou de se taire face \u00e0 des \u00ab blagues \u00bb sexistes, en remettant en question le fondement de nos gestes les plus banals, ou encore en \u00e9vitant de reconduire \u00e0 travers nos expressions quotidiennes certaines formes de st\u00e9r\u00e9otypes. Toujours, nous rendons compte que la socialisation diff\u00e9rentielle selon les sexes produit des malaises encore peu document\u00e9s. Surtout, nous militons, \u00e0 petite \u00e9chelle, loin des projecteurs, dans des milieux parfois hostiles \u00e0 nos d\u00e9constructions f\u00e9ministes. Bienvenue dans la r\u00e9alit\u00e9 !<br>\r\n<\/br>\r\n\r\nEn esp\u00e9rant que les textes rassembl\u00e9s dans ce num\u00e9ro constituent pour plusieurs des sources d\u2019inspiration, que les caract\u00e8res solitaires et solidaires des f\u00e9minismes au quotidien s\u2019encouragent et se multiplient.<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong>\r\n<br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Vol.-19-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-18-no-1-conflictuelles\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Couverture-18.png\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 27 novembre 2013<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-18-no-1-conflictuelles\/\">Vol. 18 no.1 - \u00ab\u00a0ConflictuELLES \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/sandrine-bourget-lapointe\/'>Sandrine Bourget-Lapointe<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marie-eve-campbell\/'>Marie-\u00c8ve Campbell<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/jessica-falardeau\/'>Jessica Falardeau<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/gabrielle-dore\/'>Gabrielle Dor\u00e9<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/christine-jalbert\/'>Christine Jalbert<\/a><\/div><\/section><p>Au moment o\u00f9 nous avons choisi le th\u00e8me de la revue, le conflit semblait aller de soi. Sortant tout juste d\u2019une gr\u00e8ve de plusieurs mois, la majorit\u00e9 d\u2019entre nous avait atteint la limite, celle d\u2019un trop-plein d\u2019\u00e9motions, d\u2019un bras de fer autant discursif que physique. C\u2019est d\u2019ailleurs une caract\u00e9ristique des mouvements f\u00e9ministes que d\u2019\u00eatre critique de la soci\u00e9t\u00e9 dans laquelle ils existent. Ne serait-ce que pour remettre en question le statut quo de l\u2019in\u00e9galit\u00e9 et des injustices sociales. En choisissant le th\u00e8me du conflit, nous avons voulu mettre en lumi\u00e8re que le mouvement f\u00e9ministe n\u2019\u00e9chappe pas aux multiples conflits qui l\u2019habitent en son sein, tant dans le milieu acad\u00e9mique que communautaire. Il nous a paru, bien que les conflits aient toujours exist\u00e9, qu\u2019une fa\u00e7on plus positive de les appr\u00e9hender serait vivifiante et inspirante pour le mouvement. <br>\r\n<\/br>\r\n\r\nNous avons amorc\u00e9 la r\u00e9flexion \u00e0 partir de certaines questions qui font pol\u00e9miques au sein des \u00e9tudes et du mouvement f\u00e9ministes. Des d\u00e9bats ont cours depuis plusieurs ann\u00e9es, pensons notamment \u00e0 la question de l\u2019industrie du sexe, ou encore, \u00e0 celle de la la\u00efcit\u00e9 qui est tr\u00e8s d\u00e9battue actuellement. Les divergences de points de vue peuvent cr\u00e9er des malaises et des inconforts au sein d\u2019un groupe. Pour certainEs, assumer pleinement des id\u00e9es ou un point de vue n\u2019est pas un probl\u00e8me. Pour d\u2019autres, l\u2019ambigu\u00eft\u00e9 et l\u2019h\u00e9sitation \u00e0 prendre position les confinent dans un entre-deux parfois consid\u00e9r\u00e9 comme un manque de conviction. Ainsi, ce climat de tension peut en effrayer certainEs dans les milieux militants. Pour F\u00e9min\u00c9tudes, il est \u00e9vident que le conflit n\u2019est pas toujours n\u00e9gatif; il est parfois n\u00e9cessaire pour faire avancer une r\u00e9flexion. Ne faudrait-il pas, en ce sens, commencer \u00e0 l\u2019assumer et l\u2019utiliser pour aller plus loin? Les nombreux d\u00e9bats et conflits qui soi-disant \u00ab d\u00e9chirent \u00bb le mouvement f\u00e9ministe au Qu\u00e9bec prouvent au contraire que la mouvance f\u00e9ministe est vivante, que plusieurs sujets sont toujours pertinents et que la lutte f\u00e9ministe l\u2019est sinon plus. <br>\r\n<\/br>\r\n\r\nLe projet de ce volume de F\u00e9min\u00c9tudes \u00e9tait de cr\u00e9er un espace permettant l\u2019expression du dissensus entre f\u00e9ministes. \u00c0 travers cette publication, nous esp\u00e9rons vous pr\u00e9senter une vision plus positive du conflit qui saura aller au-del\u00e0 d\u2019un discours souvent binaire qui nous demande de facto une prise de position d\u2019un c\u00f4t\u00e9 ou de l\u2019autre, excluant d\u2019importantes nuances dont il faut discuter. Les d\u00e9bats et \u00e9changes entre f\u00e9ministes permettent d\u2019alimenter nos r\u00e9flexions et d\u2019entretenir un processus de r\u00e9flexion constant quant \u00e0 notre posture f\u00e9ministe. Selon nous, les oppositions et divergences d\u2019opinions devraient \u00eatre per\u00e7ues comme un levier servant \u00e0 faire avancer les objectifs communs des femmes et ce, quelles que soient leurs exp\u00e9riences respectives.<br>\r\n<\/br>\r\n\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Vol.-18-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-17-no-1-pratiques-feministes\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Couverture-17.png\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 3 d\u00e9cembre 2012<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-17-no-1-pratiques-feministes\/\">Vol. 17 no. 1 - \u00ab\u00a0Les pratiques f\u00e9ministes \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/gabrielle-dore\/'>Gabrielle Dor\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/jessica-falardeau\/'>Jessica Falardeau<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/anissa-hachemi\/'>Anissa Hachemi<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/jessica-hamel-akre\/'>Jessica Hamel-Akr\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/caroline-jacquet\/'>Caroline Jacquet<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/christina-nitu\/'>Christina Nitu<\/a><\/div><\/section><p>Lorsque nous avons produit les premiers mots de l'appel de texte, nous n'\u00e9tions pas encore sensibles \u00e0 la v\u00e9rit\u00e9 qui se r\u00e9v\u00e9lerait derri\u00e8re ce d\u00e9fi qu'on lan\u00e7ait. Nous vous avons demand\u00e9 de r\u00e9fl\u00e9chir \u00e0 \u00ab la d\u00e9finition de notre identit\u00e9 individuelle et de cr\u00e9er les \u00e9changes pour rejoindre le collectif \u00bb. On vous a dit que le prochain num\u00e9ro \u00ab chercherait \u00e0 passer de la th\u00e9orie \u00e0 l'action \u00bb. Un an plus tard, que les \u00e9v\u00e9nements nous ont donn\u00e9 raison! <br>\r\n<\/br>\r\n\r\nNe pas \u00e9voquer le mouvement \u00e9tudiant de 2012 dans un num\u00e9ro qui s'int\u00e9resse \u00e0 un f\u00e9minisme tangible et r\u00e9alis\u00e9 serait faire une grave injustice \u00e0 nos luttes, pass\u00e9es, pr\u00e9sentes et futures. Le mouvement, venu interrompre nos r\u00e9flexions acad\u00e9miques nous a n\u00e9anmoins offert de marcher pour manifester nos f\u00e9minismes et d'exprimer notre d\u00e9saccord avec les rapports d'oppression que nous continuons de subir quotidiennement. L'\u00e9quipe de r\u00e9daction de F\u00e9min\u00c9tudes s'imaginait passer l'ann\u00e9e universitaire au calme, \u00e0 ses bureaux, \u00e0 contempler l'\u00e9tendue des pratiques f\u00e9ministes dans nos taches \u00e9ditoriales \u00e0 travers ces articles aujourd'hui publi\u00e9s. Mais, avec le recul cette ann\u00e9e a r\u00e9clam\u00e9 bien plus de concret que d'abord imagin\u00e9. Des r\u00e9unions d'\u00e9quipe aux emplois du temps charg\u00e9s, certaines priorit\u00e9s sont pass\u00e9es au second plan. Nous avons \u00e9chang\u00e9 nos plumes pour des pancartes, nous avons d\u00e9sert\u00e9 nos bureaux, nous sommes pass\u00e9es du texte au terrain. Nous nous demandons r\u00e9guli\u00e8rement: \u00ab\u00a0que va-t-il se passer ? \u00bb <br>\r\n<\/br>\r\n\r\nDans l'action politique les gestes se posent avec appr\u00e9hension. Nous vivions l'incertitude de ne pas savoir ce qu'il adviendrait finalement de nos efforts. Nous savons pourtant que la lutte que l'on essayait de faire vivre malgr\u00e9 les difficult\u00e9s contingentes dans lesquelles nous baignons, ne se laisserait pas consumer et c'est bien l\u00e0 l'objet du th\u00e8me sur lequel nous vous invitons \u00e0 r\u00e9fl\u00e9chir les enjeux de la pratique. Dans ce num\u00e9ro, des pratiques en marges \u00e0 la th\u00e9orisation de la pratique, les auteur.e.s s'interrogent sur les complexit\u00e9s li\u00e9es \u00e0 la r\u00e9alisation des f\u00e9minismes. Quil s'agisse de l'intersectionnalit\u00e9, de la cr\u00e9ation litt\u00e9raire, ou des rapports entre la m\u00e9decine et les femmes, sans oublier bien s\u00fbr l'implication f\u00e9ministe au sein de la gr\u00e8ve \u00e9tudiante, nous sommes heureuses de vous offrir ce floril\u00e8ge de textes curieux et minutieux qui cherchent \u00e0 comprendre comment le f\u00e9minisme est v\u00e9cu.<br>\r\n<\/br>\r\n\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Vol.-17-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-16-no-1-je-suis-feministe-et\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Couverture-16.png\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 2011<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-16-no-1-je-suis-feministe-et\/\">Vol. 16 no. 1 - \u00ab\u00a0Je suis f\u00e9ministe et \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/beatrice-chateauvert-gagnon\/'>B\u00e9atrice Ch\u00e2teauvert-Gagnon<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/julie-depelteau\/'>Julie Depelteau<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/jessica-hamel-akre\/'>Jessica Hamel-Akr\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/caroline-jacquet\/'>Caroline Jacquet<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/vanessa-langlois\/'>Vanessa Langlois<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/andreanne-martel\/'>Andr\u00e9anne Martel<\/a><\/div><\/section><p><em>Je suis feministe, mais...<\/em> <br>\r\nUne phrase qui revient souvent depuis quelques ann\u00e9es, avec sa formulation corollaire, mais non moins pr\u00e9sente: \u00ab Je ne suis pas f\u00e9ministe mais... \u00bb Inutile de rappeler en effet que le f\u00e9minisme a mauvaise presse et peine encore et toujours \u00e0 se forger une image positive dans les m\u00e9dias et aupr\u00e8s du (n\u00e9buleux mais non moins puissant) grand public. En effet, les st\u00e9r\u00e9otypes, les pr\u00e9jug\u00e9s, les contre-courants et autres freins sociaux ont parfois raison de l'adh\u00e9sion massive et assum\u00e9e au f\u00e9minisme.<br>\r\n<\/br>\r\n<em>Une d\u00e9finition r\u00e9ductrice de la diversit\u00e9 des identit\u00e9s et du renouveau des discours f\u00e9ministes contemporains.<\/em><br>\r\nPourtant, plusieurs (dont vous, probablement, qui lisez cette revue, et nous, qui l'avons \u00e9dit\u00e9e) se revendiquent encore, parfois fi\u00e8rement, parfois rageusement, parfois timidement, \u00e0 ce mouvement social et th\u00e9orique. Car quoi qu'en disent ou que souhaitent ses d\u00e9tracteurs, le f\u00e9minisme n'est pas mort, bien au contraire ; \u00e0 certains \u00e9gards, peut-\u00eatre a-t-il rarement \u00e9t\u00e9 aussi riche et vivant.<br>\r\n<\/br>\r\n<em>Je suis f\u00e9ministe et ! est un appel \u00e0 une formulation positive. Un appel \u00e0 la richesse, \u00e0 la diversit\u00e9, \u00e0 l'inclusion.<\/em><br>\r\nUn appel qui s'adressait donc \u00e0 vous, \u00e0 nous, ch\u00e8res f\u00e9ministes, \u00e0 \u00e9taler au grand jour nos convictions, nos r\u00e9flexions, nos passions, nos rages et nos luttes. L'appel visait \u00e0 assumer notre identification au mouvement, \u00e0 se (r\u00e9)approprier le terme, \u00e0 en faire une fiert\u00e9. Il visait \u00e0 d\u00e9cloisonner les cat\u00e9gories fixes, rejeter les \u00e9tiquettes trop faciles. Il s'ancrait dans une perspective personnelle, certes, mais appelait \u00e9galement \u00e0 d\u00e9passer ce point de d\u00e9part pour se connecter aux mouvements plus larges, \u00e0 relier le personnel au politique.<br>\r\n<\/br>\r\nSaurez-vous, vous aussi, assumer votre f\u00e9minisme, prendre position, vous d\u00e9gager des connotations, reprendre possession des mots, saisir la port\u00e9e que peut avoir la manifestation de vos convictions et ne pas vous laisser ralentir par les diff\u00e9rences d'opinion qui enrichissent le mouvement, le rendent plus puis- sant et pluriel ? \u00ab Je suis f\u00e9ministe ! Et mon f\u00e9minisme se traduit par... \u00bb ? Place \u00e0 l'affirmation!<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Vol.-16-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-15-no-1-celebrations-agir-et-penser-les-feminismes\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Couverture-15.png\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 2010<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-15-no-1-celebrations-agir-et-penser-les-feminismes\/\">Vol. 15 no. 1 - \u00ab\u00a0C\u00e9l\u00e9brations ! Agir et penser les f\u00e9minismes \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/pascale-bouchard\/'>Pascale Bouchard<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/julie-depelteau\/'>Julie Depelteau<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/rosemarie-fournier-guillemette\/'>Rosemarie Fournier-Guillemette<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/camille-fournier-tremblay\/'>Camille Fournier-Tremblay<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marie-andree-lefebvre\/'>Marie-Andr\u00e9e Lefebvre<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/stephanie-mayer\/'>St\u00e9phanie Mayer<\/a><\/div><\/section><p>L'ann\u00e9e 2010 aura \u00e9t\u00e9 celle des anniversaires: L'R des centres de femmes a fit\u00e9 ses 25 ans, Stella ses 15 ans, l'IREF a eu 20 ans et enfin, la revue F\u00e9min\u00e9tudes c\u00e9l\u00e8bre ses 15 ans avec ce num\u00e9ro festif. Il n'y a pas \u00e0 dire, les f\u00e9minismes sont sur toutes les l\u00e8vres ces temps-ci ! Et il y a de quoi se r\u00e9jouir !<br>\r\n<\/br>\r\nL'une d'entre nous a demand\u00e9 : \u00ab Et si nous discutions de ce que le titre de la revue \u00ab\u00a0C\u00e9l\u00e9brations! Agir et penser les f\u00e9minismes \u00bb am\u00e8ne de festif? En quoi tous ces anniversaires sont-ils r\u00e9jouissants? \u00bb Et la discussion \u00e9tait lanc\u00e9e pour quelques heures!<br>\r\n<\/br>\r\n\u00ab C'est important de rendre visibles les probl\u00e8mes certes, dit l'une, mais c'est tout aussi important de souligner ce qui a \u00e9t\u00e9 rendu visible \u00bb. \u00ab\u00a0C\u00e9l\u00e9brer, ce n'est pas seulement regarder les bons coups pass\u00e9s. C'est \u00e9galement regarder en avent, c'est se rendre compte qu'\u00eatre f\u00e9ministe c'est agr\u00e9able ! \u00c7a va de l'avant, dit l'autre \u00bb<br>\r\n<\/br>\r\nReconnaitre les c\u00e9l\u00e9brations lorsque l'on est f\u00e9ministe, c'est d'abord marcher sur un fil t\u00e9nu. Le fil est mince entre ce que nous avons acquis et ce que nous pouvons perdre et il reste encore tellement de chemin \u00e0 faire! Mais \u00e0 mesure que l'on souligne les raisons de c\u00e9l\u00e9brer les rencontres, les \u00e9changes, les apprentissages, les d\u00e9fis, les d\u00e9couvertes, la jole qu'apporte le fait d'\u00eatre f\u00e9ministe, de quoi perdre le fil! On se rend compte que c\u00e9l\u00e9brer est une autre fa\u00e7on de reconna\u00eetre de ce que les f\u00e9minismes rendent possible.<br>\r\n<\/br>\r\n\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Vol.-15-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a>\r\n<\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-14-no-1-feminismes-et-diversites-culturelles\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Couverture-14.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 2009<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-14-no-1-feminismes-et-diversites-culturelles\/\">Vol. 14 no. 1 - \u00ab\u00a0F\u00e9minismeS et diversit\u00e9S culturelleS \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/pascale-bouchard\/'>Pascale Bouchard<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/raphaelle-damours\/'>Raphaelle D'Amours<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/julie-depelteau\/'>Julie Depelteau<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/rosemarie-fournier-guillemette\/'>Rosemarie Fournier-Guillemette<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/stephanie-mayer\/'>St\u00e9phanie Mayer<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/maxime-nadeau\/'>Maxime Nadeau<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/elona-ritchie\/'>Elona Ritchie<\/a><\/div><\/section><p>Il y a maintenant un an que le comit\u00e9 de r\u00e9daction de <em>F\u00e9min\u00c9tudes<\/em> lan\u00e7ait un appel de textes sous le th\u00e8me \u00ab F\u00e9minismeS et diversit\u00e9S culturelleS \u00bb. \u00c0 ce moment, une ann\u00e9e s'\u00e9tait \u00e9coul\u00e9e depuis la saga publique et politique de la Commission Bouchard-Taylor. Le comit\u00e9 avait envie d'offrir un espace de r\u00e9flexion afin d'aborder les diverses probl\u00e9matiques reli\u00e9es au post-colonialisme, aux diff\u00e9rences culturelles, au multiculturalisme, aux rapports interculturels ainsi qu'aux discours et pratiques f\u00e9ministes majoritaires. Le volet critique de cette d\u00e9marche \u00e9tait central pour le comit\u00e9 de r\u00e9daction : nous avions le d\u00e9sir de donner une voix aux personnes critiques des pratiques et discours dominants, et surtout d'offrir une tribune \u00e0 celles que ces m\u00eames discours et pratiques affectent afin d'entendre leur parole, mais aussi leur col\u00e8re. Depuis quelques d\u00e9cennies d\u00e9j\u00e0, les \u00e9tudes critiques de l'orientalisme, du post-colonialisme et du racisme prennent de l'ampleur dans divers d\u00e9partements, o\u00f9 les f\u00e9minismes acad\u00e9miques sont int\u00e9gr\u00e9s, afin d'amener chacun.e \u00e0 questionner, la mani\u00e8re dont elles et ils construisent et maintiennent des divisions, des exclusions ainsi que des hi\u00e9rarchies.<br>\r\n<\/br>\r\nEn raison du th\u00e8me et des perspectives critiques retenus, nous avions deux objectifs pour ce 14 volume de <em>F\u00e9min\u00c9tudes<\/em>. Premi\u00e8rement, \u00e9couter les r\u00e9flexions critiques des intellectuel.le.s et des militante.s marginalis\u00e9.e.s par les interventions et les th\u00e9ories f\u00e9ministes occidentalocentr\u00e9es, dans le contexte qu\u00e9b\u00e9cois. Deuxi\u00e8mement, laisser un espace pour que les \u00e9tudiant.e.s, les femmes et les f\u00e9ministes majoritaires proc\u00e8dent \u00e0 une critique de leur r\u00f4le dans le maintien du racisme et d'ombre du colonialisme.<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Vol.-14-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-13-no-1-femmes-sur-la-scene-publique\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Couverture-13.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 2008<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-13-no-1-femmes-sur-la-scene-publique\/\">Vol. 13 no. 1 - \u00ab Femmes sur la sc\u00e8ne publique : visibilit\u00e9s subversives \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/mylene-bedard\/'>Myl\u00e8ne B\u00e9dard<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/pascale-bouchard\/'>Pascale Bouchard<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/melanie-cere\/'>M\u00e9lanie C\u00e9r\u00e9<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/julie-depelteau\/'>Julie Depelteau<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/isabelle-dumont\/'>Isabelle Dumont<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/lydia-halley-soucy\/'>Lydia Halley Soucy<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/mariane-leonard\/'>Mariane L\u00e9onard<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marie-pier-ouellette\/'>Marie-Pier Ouellette<\/a><\/div><\/section><p>Femmes visibles, femmes de t\u00eate, femmes fortes, femmes cach\u00e9es, oubli\u00e9es, retir\u00e9es. Mais femmes toujours ! Et quelles femmes !<br>\r\n<\/br>\r\nLes visibilit\u00e9s subversives s'inscrivent dans le quotidien, dans des actes multiples, petits comme grands. Actes qui ne sont pas toujours coh\u00e9rents, compl\u00e9mentaires les uns aux autres. C'est ce que cette \u00e9dition de F\u00e9min\u00c9tudes se veut livrer et \u00eatre.<br>\r\n<\/br>\r\nDe l'essai au texte d'opinion, en passant par le texte de cr\u00e9ation, cette \u00e9dition propose des pistes de r\u00e9flexion concernant les multiples enjeux et d\u00e9fis de la visibilit\u00e9 sociale des femmes.<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/10\/Vol.-13-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a>\r\n<\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-12-no-1-feminismes-de-demain\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Couverture-12-1.png\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 2007<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-12-no-1-feminismes-de-demain\/\">Vol. 12 no. 1 - \u00ab F\u00e9minismes de demain : enjeux et d\u00e9fis \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/isabelle-courcy\/'>Isabelle Courcy<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/sophie-le-blanc\/'>Sophie le Blanc<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/noemi-ral\/'>No\u00ebmi Ral<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/karina-victoria-sieres\/'>Karina Victoria Sieres<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/amelie-tremblay\/'>Am\u00e9lie Tremblay<\/a><\/div><\/section><p>Ces derni\u00e8res ann\u00e9es, le f\u00e9minisme a fait l'objet de fortes critiques de part et d'autre. C'est dans un tel contexte que l'\u00e9quipe de F\u00e9min\u00c9tudes a d\u00e9cid\u00e9 de se pencher sur les enjeux et d\u00e9fis des f\u00e9minismes de demain convaincue que leurs revendications sont toujours d'actualit\u00e9. Ceux et celles qui ont r\u00e9pondu \u00e0 notre appel vous proposent des pistes de r\u00e9flexion sur ce th\u00e8me par l'interm\u00e9diaire de textes vari\u00e9s allant de l'essai \u00e0 la lettre d'opinion, en passant par le r\u00e9cit d'exp\u00e9rience et le texte de cr\u00e9ation. <br>\r\n<\/br>\r\nLa revue se distingue par sa forme h\u00e9t\u00e9roclite et plurielle. Riche de cette diversit\u00e9, elle pr\u00e9sente des \u00e9crits qui sont fa\u00e7onn\u00e9s par des savoirs \u00e0 la fois acad\u00e9miques et exp\u00e9rientiels. Rassemblant des points de vue \u00e9clectiques, parfois m\u00eame divergents, cette \u00e9dition collective refl\u00e8te les id\u00e9aux, les perspectives, les moyens et les lieux investis par les auteur-es pour faire avancer la cause f\u00e9ministe. Certains des enjeux soulev\u00e9s sont \u00e0 l'agenda depuis longtemps et d'autres s'y sont ajout\u00e9s depuis peu. Quoiqu'il en soit, ils s'inscrivent dans le pr\u00e9sent et orientent les luttes actuelles et futures.<br>\r\n<\/br> \r\nDans la foul\u00e9e des textes qui composent cette \u00e9dition de F\u00e9min\u00c9tudes, d'autres d\u00e9fis viennent s'ajouter. Un premier : s'interroger sur les sch\u00e8mes de domination que nous pouvons en tant que f\u00e9ministes reproduire. Ainsi, s'impose la n\u00e9cessit\u00e9 de tenir compte du contexte et de prendre conscience de nos cadres de r\u00e9f\u00e9rence dans l'\u00e9tude du militantisme des femmes d'ici et d'ailleurs. Un second: favoriser l'\u00e9change et le dialogue entre les f\u00e9ministes des divers horizons. Au-del\u00e0 des fondements th\u00e9oriques et des postulats \u00e9pist\u00e9mologiques diff\u00e9rents, nous croyons que des rapprochements peuvent se r\u00e9aliser, et ce, \u00e0 l'avantage de tous et de toutes.<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br> \r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Vol.-12-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-11-no-1-femmes-et-militantisme\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Couverture-11.png\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 2006<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-11-no-1-femmes-et-militantisme\/\">Vol. 11 no. 1 - \u00ab\u00a0Femmes et militantisme \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/janie-beauchamp\/'>Janie Beauchamp<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/tanya-dery-obin\/'>Tanya D\u00e9ry-Obin<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/julie-dupuis\/'>Julie Dupuis<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/veronique-labelle\/'>V\u00e9ronique Labelle<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/genevieve-lafleur\/'>Genevi\u00e8ve Lafleur<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/sophie-le-blanc\/'>Sophie le Blanc<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/anahi-morales\/'>Anahi Morales<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/audrey-rousseau\/'>Audrey Rousseau<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/roxanne-couture\/'>Roxanne Couture<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/pascale-brunet\/'>Pascale Brunet<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/sarah-claude-racicot\/'>Sarah-Claude Racicot<\/a><\/div><\/section><p>Je suis une femme. Qu'est-ce que cela peut bien vouloir dire? Qu'est-ce que cela peut bien sous-entendre? Suffit-il que j'en ai la forme et les traits? Suffit-il que mon sexe crie l'\u00e9vidence? Suffira-t-il que j'ignore toute sa charge, son pass\u00e9, suffira-t-il que j'\u00e9touffe l'\u00e9cho de ces autres qui me composent aujourd'hui, qui m'ont ouvert le chemin et qui ont si courageusement et si fi\u00e8rement empoign\u00e9 le pinceau et octroy\u00e9 avec passion les couleurs qui dessinent l'univers des possibles qui s'ouvrent \u00e0 moi? Suffira-t-il que j'oublie, que je nie, que je me vautre dans ce sexe pour \u00eatre une femme? Je ne saurais y pr\u00e9tendre sans imposer ma volont\u00e9. Lutter sans violence dans l'espace o\u00f9 je prends forme. Prendre la main des autres femmes, me rallier \u00e0 elles et, d'un air assur\u00e9, laisser planer autour de nous le chant de nos convictions. J'entends cette rumeur f\u00e9minine, si acharn\u00e9e, d'un continent \u00e0 l'autre, d'un oc\u00e9an \u00e0 l'autre. Ces femmes de mines et de langages diff\u00e9rents et pourtant si semblables, si d\u00e9termin\u00e9es \u00e0 donner un sens, une raison d'\u00eatre \u00e0 ce sexe. Plus obstin\u00e9es encore \u00e0 construire une image renouvel\u00e9e, diversifi\u00e9e, un \u00ab je \u00bb conscient de lui- m\u00eame et du monde. Moi, une femme parmi les femmes, je peux, je peux beaucoup. Je peux faire entendre ma voix, l'ajouter au nombre des autres, militer pour un espace o\u00f9 je puisse laisser libre cours \u00e0 ma subjectivit\u00e9, militer pour l'\u00e9panouissement du milieu o\u00f9 j'\u00e9volue. J'incarnerai donc ce sexe avec le savoir de la responsabilit\u00e9 qui m'incombe.<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Vol.-11-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-10-no-1-femmes-et-egalite\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Couverture-10.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 2005<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-10-no-1-femmes-et-egalite\/\">Vol. 10 no. 1 - \u00ab\u00a0Femmes et \u00e9galit\u00e9 \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marie-claude-laberge\/'>Marie-Claude Laberge<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/isabelle-marchand\/'>Isabelle Marchand<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marie-belle-ouellet\/'>Marie-Belle Ouellet<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/annie-rousseau\/'>Annie Rousseau<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/fannie-sauve\/'>Fannie Sauv\u00e9<\/a><\/div><\/section><p>Depuis des d\u00e9cennies, sous une pl\u00e9iade de fronts, des milliers de femmes d'ici et d'ailleurs luttent quotidiennement contre les discriminations qu'elles subissent et combattent courageusement les divers syst\u00e8mes d'oppression, dont elles sont trop souvent les premi\u00e8res victimes (e.g patriarcat, capitalisme, racisme, etc.). Certaines y risquent m\u00eame leur vie. Au Qu\u00e9bec, la mouvance f\u00e9ministe, \u00e9mergeant de la contestation sociale des ann\u00e9es 1960-1970, a incite les diff\u00e9rents gouvernements du Qu\u00e9bec \u00e0 adopter une kyrielle de lois et de politiques sociales ayant trait \u00e0 l'\u00e9galit\u00e9 entre les sexes: une valeur que se devait de promouvoir l'\u00c9tat en tant que r\u00e9gulateur d'une soci\u00e9t\u00e9 qui se voulait moderne et d\u00e9mocratique. \u00c0 ce chapitre, mentionnons notamment l'av\u00e8nement de la Charte des droits et libert\u00e9s de la personne, adopt\u00e9e en 1975, qui a consacr\u00e9 l'\u00e9galit\u00e9 de toute personne sans distinction, exclusion ou pr\u00e9f\u00e9rence (article 10). Depuis, plusieurs actions positives ont \u00e9t\u00e9 initi\u00e9es et mises en \u0153uvre dans diverses sph\u00e8res d'activit\u00e9s, afin de contrer et de corriger la discrimination syst\u00e9mique exerc\u00e9e \u00e0 l'endroit des femmes. <br>\r\n<\/br>\r\nAinsi, apr\u00e8s toutes ces ann\u00e9es de militantisme, les b\u00e9n\u00e9fices de nos avanc\u00e9es ont-ils cristallis\u00e9 cette \u00e9galit\u00e9 qui nous est si ch\u00e8re? Et pourquoi donc ressasser cette \u00e9pineuse question de l'\u00e9galit\u00e9 entre les femmes et les hommes puisque, selon les croyances populaires, les femmes sont maintenant \u00e9gales...\u00bb, et que d'autres n\u00e9ophytes clament &lt;qu&#039;elles sont all\u00e9es trop loin...? Et bien la r\u00e9ponse est fort simple: les femmes, jeunes et moins jeunes, se heurtent et encaissent encore les contrecoups d&#039;une organisation sociale qui reproduit les in\u00e9galit\u00e9s et par ricochet, la discrimination, voire l&#039;oppression. Si l&#039;\u00e9galit\u00e9 de droits nous est d\u00fbment acquise par les lois \u00e9tatiques, l&#039;\u00e9galit\u00e9 de faits, c&#039;est-\u00e0-dire celle que nous exp\u00e9rimentons dans la r\u00e9alit\u00e9 quotidienne, reste \u00e0 conqu\u00e9rir. Certes plus insidieuse que les aberrations qu&#039;ont combattues et\/ou subies nos m\u00e8res et nos grands-m\u00e8res, l&#039;in\u00e9galit\u00e9 se polarise toujours tant dans la sph\u00e8re priv\u00e9e que publique et ce, en d\u00e9pit de l&#039;\u00e9volution des mentalit\u00e9s: les r\u00f4les et st\u00e9r\u00e9otypes sexuels sont tenaces et leur \u00e9vanescence exige vigilance et d\u00e9termination continuelles.<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Vol.-10-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-09-no-1-femmes-et-pouvoirs\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Couverture-09.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 2004<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-09-no-1-femmes-et-pouvoirs\/\">Vol. 09 no. 1 - \u00ab\u00a0Femmes et pouvoirs : \u00e0 la conqu\u00eate des territoires \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marie-eve-belanger\/'>Marie-Eve B\u00e9langer<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marie-claude-laberge\/'>Marie-Claude Laberge<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marise-mathieu\/'>Marise Mathieu<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marie-belle-ouellet\/'>Marie-Belle Ouellet<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/judith-patenaude\/'>Judith Patenaude<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/roxanne-ruel\/'>Roxanne Ruel<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/fannie-sauve\/'>Fannie Sauv\u00e9<\/a><\/div><\/section><p><em>Femmes<\/em> et <em>Pouvoirs<\/em>, voil\u00e0 deux termes qui, il n'y a encore pas si longtemps, s'excluaient mutuellement - antagonistes de par leur d\u00e9finition sociale, culturelle et historique. Depuis maintenant plus d'un si\u00e8cle, avec l'av\u00e8nement du f\u00e9minisme, les femmes ont heureusement pu regagner une partie du terrain perdu ou, du moins, une certaine autonomie d'action dans les diff\u00e9rentes sph\u00e8res de leur vie. Cependant, malgr\u00e9 ces grandes avanc\u00e9es, le th\u00e8me du pouvoir au f\u00e9minin demeure encore aujourd'hui une notion bien myst\u00e9rieuse et... controvers\u00e9e. <br>\r\n<\/br>\r\nAvec le num\u00e9ro F\u00e9min\u00e9tudes de cette ann\u00e9e, nous nous sommes demand\u00e9 s'il y avait, au del\u00e0 des traditionnels pouvoirs attribu\u00e9s aux femmes, un pouvoir sp\u00e9cifiquement f\u00e9minin. Nous avons interrog\u00e9 l'avancement des luttes f\u00e9ministes autant dans les sph\u00e8res publiques que priv\u00e9es. Nous voulons savoir de quelle(s) mani\u00e8re(s) les femmes prennent le pouvoir et de quelles fa\u00e7ons elles l'exercent.<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Vol.-9-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-08-no-1-jeunes-et-societe\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Couverture-08.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 2003<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-08-no-1-jeunes-et-societe\/\">Vol. 08 no. 1 - \u00ab\u00a0Jeunes et soci\u00e9t\u00e9 : kal\u00e9idoscope d&#039;une g\u00e9n\u00e9ration \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marie-eve-belanger\/'>Marie-Eve B\u00e9langer<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marili-bordeleau-desrochers\/'>Marili Bordeleau-Desrochers<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/christelle-lebreton\/'>Christelle Lebreton<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/judith-patenaude\/'>Judith Patenaude<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/roxanne-ruel\/'>Roxanne Ruel<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marie-eve-surprenant\/'>Marie-Eve Surprenant<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/catherine-veronneau\/'>Catherine V\u00e9ronneau<\/a><\/div><\/section><p>Nous nous sommes int\u00e9ress\u00e9es cette ann\u00e9e \u00e0 la jeune g\u00e9n\u00e9ration, la n\u00f4tre en l'occurrence, pour tenter de savoir comment elle se portait et ce qu'elle avait \u00e0 dire. Le pr\u00e9sent num\u00e9ro de F\u00e9min\u00c9tudes, intitul\u00e9 Jeunes et soci\u00e9t\u00e9 : kal\u00e9idoscope d'une g\u00e9n\u00e9ration, dresse le portrait des jeunes, surtout des jeunes femmes et du f\u00e9minisme en ce d\u00e9but de nouveau mill\u00e9naire, mill\u00e9naire ayant d\u00e9but\u00e9 dans un contexte mondial complexe. Bien s\u00fbr, les jeunes (hommes et femmes) ont de nombreux points en commun: la vingtaine est l'un des moments o\u00f9 plusieurs d\u00e9cisions fondamentales sont \u00e0 prendre (choix de sa carri\u00e8re, engagement amoureux, d\u00e9sir d'enfant) et ils doivent faire face \u00e0 des r\u00e9alit\u00e9s complexes (crise \u00e9cologique, perte de la s\u00e9curit\u00e9 d'emploi, paradoxe individualisme versus mondialisation, etc.). Jeunes hommes et jeunes femmes se rejoignent sur plusieurs plans, mais dans le quotidien, ils et elles se heurtent \u00e0 des obstacles diff\u00e9rents selon le sexe : \u00e9quit\u00e9 salariale, pr\u00e9carit\u00e9 d'emploi, r\u00e9ussite scolaire, articulation travail-famille, etc. On retrouve autant de jeunes engag\u00e9s et militants que de jeunes d\u00e9sint\u00e9ress\u00e9s et d\u00e9sengag\u00e9s.<br>\r\n<\/br>\r\nNous esp\u00e9rons grandement que ce num\u00e9ro Jeunes et soci\u00e9t\u00e9 : kal\u00e9idoscope d'une g\u00e9n\u00e9ration suscitera de nombreuses pistes de r\u00e9flexion. Les jeunes sauront-ils, malgr\u00e9 leurs divergences, mettre en commun leurs aspirations, leur d\u00e9sir de changement afin que puisse s'amorcer une (re)conscientisation sociale faite d'\u00e9galit\u00e9 et de justice? Cette derni\u00e8re ne peut d\u00e9buter qu'avec une r\u00e9flexion profonde sur les rapports sociaux de sexe et de genre et leurs effets sur la hi\u00e9rarchisation sociale afin d'en venir \u00e0 un mod\u00e8le de transformation sociale qui prenne en compte chaque individu pour ce qu'il est et non pour ce qu'il est suppos\u00e9 \u00eatre ou ce qu'il devrait \u00eatre.<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Vol.-8-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-07-no-1-femmes-et-sexualites\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Couverture-07.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 2002<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-07-no-1-femmes-et-sexualites\/\">Vol. 07 no. 1 - \u00ab\u00a0Femmes et sexualit\u00e9(s) \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/christelle-lebreton\/'>Christelle Lebreton<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/karine-tremblay\/'>Karine Tremblay<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marie-eve-surprenant\/'>Marie-Eve Surprenant<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/catherine-veronneau\/'>Catherine V\u00e9ronneau<\/a><\/div><\/section><p>Qu'en est-il de la sexualit\u00e9 des femmes? Ou plut\u00f4t, qu'en est-il des sexualit\u00e9s des femmes? \u00c0 notre avis, il est de plus en plus difficile maintenant de parler de la femme, comme d'une personne ou des femmes comme repr\u00e9sentantes de la classe des femmes. Les femmes sont plurielles et multiples. Elles peuvent porter diverses identit\u00e9s au cours de leur vie et m\u00eame plusieurs \u00e0 la fois (femme, m\u00e8re, immigrante, lesbienne, militante, \u00e9tudiante, etc.). Si nous consid\u00e9rons que les femmes sont plurielles, diff\u00e9rentes les unes des autres, il devrait en \u00eatre ainsi de leur sexualit\u00e9. Non seulement il y a des sexualit\u00e9s diff\u00e9rentes pour chaque femme, mais une femme peut aussi avoir plusieurs formes de sexualit\u00e9(s). La sexualit\u00e9 ne forme pas un tout homog\u00e8ne, stable et immuable. \u00c0 l'instar de l'orientation sexuelle, qui peut \u00eatre mouvante, changeante, la sexualit\u00e9 peut prendre diff\u00e9rents aspects selon les \u00e9tapes de la vie des femmes ou selon les exp\u00e9riences de vie, les partenaires (ou l'absence de partenaire), etc. Ce sont donc, les sexualit\u00e9s, dans toutes leurs formes, leurs myst\u00e8res, leurs diff\u00e9rences que nous avons voulu questionner dans ce num\u00e9ro. <br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Vol.-7-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-06-no-1-identites-et-alterites\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Couverture-06.png\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 2001<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-06-no-1-identites-et-alterites\/\">Vol. 06 no. 1 - \u00ab Identit\u00e9s et alt\u00e9rit\u00e9s : formes et discours \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/rebecca-beauvais\/'>R\u00e9becca Beauvais<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/elise-bergeron\/'>\u00c9lise Bergeron<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/julie-brunet\/'>Julie Brunet<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/evelyne-l-beaugrand\/'>Evelyne L-Beaugrand<\/a><\/div><\/section><p>L'\u00e9quipe de la revue F\u00e9min\u00c9tudes est fi\u00e8re, encore cette ann\u00e9e, de vous proposer un num\u00e9ro qui se veut un regard neuf sur les probl\u00e9matiques d'identit\u00e9 de genre. En effet, nous voulions vous offrir un regard pluridisciplinaire sur les identit\u00e9s de genre autour des axes de construction des identit\u00e9s et des rapports entre ces identit\u00e9s. Ce th\u00e8me, cher aux \u00e9tudes f\u00e9ministes et, dans une plus large mesure, aux \u00e9tudes sur les femmes, car il \u00ab&lt;est un \u00e9l\u00e9ment constitutif de rapports sociaux fond\u00e9s sur les diff\u00e9rences per\u00e7ues entre les sexes, et [qu&#039;il] est une fa\u00e7on premi\u00e8re de signifier les rapports de pouvoir \u00bb (Scott, 1988, 181), est travers\u00e9 par diff\u00e9rentes th\u00e9ories et remises en question fort stimulantes depuis quelques ann\u00e9es.<br>\r\n<\/br>\r\nLe volume 6 de la revue F\u00e9min\u00c9tudes est donc le r\u00e9sultat de plusieurs textes de collaboratrices ext\u00e9rieures et des membres du comit\u00e9 de r\u00e9daction qui, sans pr\u00e9tendre faire le tour de la question, tente d'ouvrir la r\u00e9flexion sur les concepts d'identit\u00e9 de genre, leurs capacit\u00e9s et leurs limites d'analyse. Ce nouveau num\u00e9ro r\u00e9unit des textes portant sur les th\u00e8mes de l'autobiographie, du rapport entre les identit\u00e9s nationale et sexu\u00e9e et de la transgression des identit\u00e9s. <br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Vol.-6-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-05-no-1-les-femmes-et-lart\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/Couverture-05.png\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 2000<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-05-no-1-les-femmes-et-lart\/\">Vol. 05 no. 1 - \u00ab Les femmes et l&#039;art : de muses \u00e0 cr\u00e9atrices \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/genevieve-proulx\/'>Genevi\u00e8ve Proulx<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/rebecca-beauvais\/'>R\u00e9becca Beauvais<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/julie-brunet\/'>Julie Brunet<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/julie-ouellette\/'>Julie Ouellette<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/julie-lavoie\/'>Julie Lavoie<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/ann-rachele-dupuis\/'>Ann-Rach\u00e8le Dupuis<\/a><\/div><\/section><p>Le volume 5 de la revue F\u00e9min\u00c9tudes se veut, cette ann\u00e9e, une tribune d'\u00e9changes et de r\u00e9flexions sur l'art des femmes, l'art f\u00e9ministe et les repr\u00e9sentations de femmes dans l'art. Cette \u00e9dition de la revue se donnait comme d\u00e9fi une meilleure compr\u00e9hension des ambitions et des conceptions de la soci\u00e9t\u00e9 des femmes artistes. Nous invitions donc les diff\u00e9rentes collaboratrices, ainsi que nous- m\u00eames, \u00e0 poser un regard neuf sur la repr\u00e9sentation des femmes dans les diff\u00e9rentes formes artistiques, sur leur place dans les univers cr\u00e9ateurs et les industries de l'art, et sur la construction de l'identit\u00e9 dans l'art. Qui plus est, nous voulions \u00e9galement en profiter pour donner la parole \u00e0 ces femmes artistes.<br>\r\n<\/br>\r\nF\u00e9minEtudes r\u00e9unit donc des textes de professeures, de charg\u00e9es de cours, ainsi que d'\u00e9tudiantes au premier, deuxi\u00e8me et troisi\u00e8me cycles. Ce num\u00e9ro questionne plus particuli\u00e8rement la place des femmes dans l'histoire de l'art et l'art comme lieu de revendication et d'intervention sociales. De la peinture murale des femmes Kassena au corps comme mat\u00e9riau artistique, du post- modernisme dans l'art au cin\u00e9ma des femmes, divers sujets sont abord\u00e9s dans ces pages. Trois entrevues, avec Denise Boucher, Louise Carr\u00e9 et Pol Pelletier, y sont \u00e9galement pr\u00e9sent\u00e9es. Par ailleurs, avec ses rubriques litt\u00e9rature, cr\u00e9ation et art engag\u00e9, ses articles portant sur des \u00e9v\u00e9nements, tels que la Marche mondiale des femmes de l'an 2000, nous esp\u00e9rons que le pr\u00e9sent num\u00e9ro saura vous int\u00e9resser.<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/11\/vol.-5_complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-04-no-1-femmes-du-siecle\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/01\/Couverture-04.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 1999<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-04-no-1-femmes-du-siecle\/\">Vol. 04 no. 1 - \u00ab\u00a0Femmes du si\u00e8cle \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/genevieve-proulx\/'>Genevi\u00e8ve Proulx<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/rebecca-beauvais\/'>R\u00e9becca Beauvais<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/julie-brunet\/'>Julie Brunet<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/julie-ouellette\/'>Julie Ouellette<\/a><\/div><\/section><p>Cette ann\u00e9e, F\u00e9min\u00c9tudes invitait les \u00e9tudiants et \u00e9tudiantes \u00e0 r\u00e9fl\u00e9chir sur l'\u00e9volution du f\u00e9minisme, de la situation des femmes et des rapports de sexe dans les soci\u00e9t\u00e9s. L'\u00e9poque qui s'ach\u00e8ve et l'av\u00e8nement d'un nouveau si\u00e8cle nous apparaissaient en effet comme l'occasion de dresser des bilans, de souligner les acquis des femmes, de nous situer dans l'histoire du f\u00e9minisme, de revisiter ses assises th\u00e9oriques, en m\u00eame temps que de nous interroger sur ses nouvelles avenues de recherche et sur les d\u00e9fis qui l'attendent. <br>\r\n<\/br>\r\nLe pr\u00e9sent num\u00e9ro r\u00e9unit donc des textes d'\u00e9tudiantes de premier et de deuxi\u00e8me cycle, ainsi que ceux de deux professeures. De la politique \u00e0 la litt\u00e9rature, en passant par la technologie et les troubles alimentaires, la vari\u00e9t\u00e9 de sujets et de perspectives qu'on trouve dans ces pages t\u00e9moigne non seulement du caract\u00e8re pluridisciplinaire des \u00e9tudes f\u00e9ministes, mais aussi de l'un des objectifs principaux de la revue permettre l'expression d'une multiplicit\u00e9 de points de vue sur les femmes et le f\u00e9minisme.<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/01\/Vol.-4-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-03-no-1-une-revue-a-soi\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/01\/Couverture-03.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 1997<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-03-no-1-une-revue-a-soi\/\">Vol. 03 no. 1 - \u00ab\u00a0Une revue \u00e0 soi \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/marise-bachand\/'>Marise Bachand<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/manon-fontaine\/'>Manon Fontaine<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/nadia-gagne\/'>Nadia Gagn\u00e9<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/brigitte-robert\/'>Brigitte Robert<\/a><\/div><\/section><p>Quatre filles,<br>\r\nQuatre chambres,<br>\r\nLe d\u00e9sir d'en sortir,<br>\r\nUne revue f\u00e9ministe.<br>\r\nPourquoi ?<br>\r\nPour une parole qui lib\u00e8re enfin.<br>\r\nVous aussi,<br>\r\nSortez de votre chambre.<br>\r\nEt tournez la page...<br>\r\nVirginia Woolf,<br>\r\nMicheline de S\u00e8ve,<br>\r\nMarie-Andr\u00e9e Roy,<br>\r\nSappho,<br>\r\nBetty Friedan,<br>\r\nShania Twain,<br>\r\nAdrienne Rich...<br>\r\nvous ouvrent leur porte...<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/01\/Vol.-3-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-02-no-1-terres-des-femmes\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/01\/Couverture-02.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 1996<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-02-no-1-terres-des-femmes\/\">Vol. 02 no. 1 - \u00ab\u00a0Terre(s) des femmes ? \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/anne-deret\/'>Anne Deret<\/a>, <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/sylvie-lamarre\/'>Sylvie Lamarre<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/nathalie-ricard\/'>Nathalie Ricard<\/a><\/div><\/section><p>Comment parler d'ailleurs ? Comment faire pour que nos grilles d'analyse voyagent ? Quelle optique choisir pour comprendre, analyser et agir sans froisser nos identit\u00e9s respectives ? En d\u00e9finitive, comment faire pour que les multiples voix du f\u00e9minin s'entendent et se fassent entendre ?<br>\r\n<\/br>\r\nLa marche des femmes contre la pauvret\u00e9 au printemps dernier a mis en \u00e9vidence notre capacit\u00e9 \u00e0 cr\u00e9er des alliances. Mais si notre identit\u00e9 de femme nous permet de faire des liens, de tracer des chemins o\u00f9 nous pouvons mieux nous comprendre, la route n'est pas toujours ais\u00e9e. Il nous faut apprendre \u00e0 conjuguer nos diverses identit\u00e9s sur le mode du dialogue. Comme nous le faisait remarquer Fran\u00e7oise Collin, philosophe et \u00e9crivaine, au cours des s\u00e9minaires qu'elle est venue donner cet automne \u00e0 l'IREF, le f\u00e9minisme n'\u00e9tait pas pr\u00e9par\u00e9 \u00e0 la pluralit\u00e9 de l'Un. Et si La femme semble insaisissable, les femmes existent et ont besoin de se b\u00e2tir un espace d'\u00e9change. <br>\r\n<\/br>\r\nLe d\u00e9veloppement de la pens\u00e9e f\u00e9ministe nous montre de plus en plus la n\u00e9cessit\u00e9 de penser le f\u00e9minin dans les diff\u00e9rences, non seulement sur le plan pratique, au niveau des rapports que nous \u00e9tablissons les unes avec les autres, mais encore au niveau de la r\u00e9flexion th\u00e9orique que nous tentons de d\u00e9velopper. Le cheminement de la pens\u00e9e n'est heureusement pas univoque et il peut para\u00eetre difficile \u00e0 certaines de d\u00e9construire des th\u00e9ories qu'elles n'ont ni construites ni utilis\u00e9es. Si l'on a tendance \u00e0 ne voir de la culture ou du culturel que chez les autres, les voix (voies) du f\u00e9minisme qui s'\u00e9l\u00e8vent de plus en plus peuvent nous permettre de saisir les multiples facettes de l'identit\u00e9-femme.<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/01\/Vol.-2-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><div class=\"row my-6 item-article\"><div class=\"col-12 col-md-2 d-flex justify-content-center justify-content-md-start pl-md-0 mb-3 mb-md-0 order-2 order-md-1\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-01-no-1-la-vague-antifeministe\/\"><img decoding=\"async\" loading=\"lazy\" class=\"img-fluid\" src=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/01\/Couverture-01.jpg\" alt=\"\"><\/a><\/div><div class=\"col-12 col-md-10 order-1 order-md-2\"><div class=\"post-metadata m-0\"><span class=\"date-published\">Publi\u00e9 le 1 janvier 1995<\/span><\/div><h3 class=\"entry-title-revues mt-3\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros\/vol-01-no-1-la-vague-antifeministe\/\">Vol. 01 no. 1 - \u00ab La vague antif\u00e9ministe \u00bb<\/a><\/h3><section class=\"item author-list mb-3\"><div class=\"author-list mb-3\" itemprop=\"creator\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">Sous la direction de <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/audrey-cote\/'>Audrey C\u00f4t\u00e9<\/a> et <a href='https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/sylvie-lamarre\/'>Sylvie Lamarre<\/a><\/div><\/section><p>N'est-ce pas d\u00e9mod\u00e9, voire r\u00e9trograde de consid\u00e9rer le f\u00e9minisme imp\u00e9ratif \u00e0 l'\u00e9volution de la soci\u00e9t\u00e9 qu\u00e9b\u00e9coise? Voil\u00e0 des questions que certaines, certains d'entre vous ont d\u00fb formuler avant d'oser entreprendre la lecture de <em>F\u00e9min\u00c9tudes<\/em> Le projet d'une revue f\u00e9ministe \u00e0 l'UQAM a vu le jour en avril dernier alors que la c\u00e9l\u00e8bre militante fran\u00e7aise, Benoite Groult, r\u00e9pondait \u00e0 l'invitation de l'Institut de Recherches et d'\u00c9tudes F\u00e9ministes (IREF). Venue au qu\u00e9bec pour la promotion de son dernier ouvrage, <em>Cette m\u00e2le assurance<\/em>, celle-ci en a profit\u00e9 pour d\u00e9plorer la disparition de publications \u00e0 caract\u00e8re f\u00e9ministe au Qu\u00e9bec, manifestement \u00e0 l'avantage des magazines f\u00e9minins perp\u00e9tuant les st\u00e9r\u00e9otypes de la femme belle, docile, maternelle et de la m\u00e9nag\u00e8re. <br>\r\n<\/br>\r\nDe l\u00e0, s'est affirm\u00e9 le d\u00e9sir de cr\u00e9er un lieu de r\u00e9flexion et d'expression pour celles qui refusent de se r\u00e9signer aux assertions apocalyptiques du discours ambiant. Non, le f\u00e9minisme n'est pas mort. Abasourdi, certes, car ses adh\u00e9rentes doivent le porter \u00e0 contre- courant et braver l'id\u00e9ologie antif\u00e9ministe qui s\u00e9vit actuellement, mais toujours vivant, \u00e0 preuve la naissance de l'IREF et celle de la pr\u00e9sente revue en pleine p\u00e9riode dite postf\u00e9ministe, pour ne citer que ces exemples. Mais, surtout, le f\u00e9minisme doit survivre pour toutes les femmes. Aujourd'hui, soit presque un an apr\u00e8s l'\u00e9tincelle, le r\u00eave qu'alluma en nous Beno\u00eete Groult voit sa concr\u00e9tisation. Le recul du f\u00e9minisme et la progression de l'antif\u00e9minisme constituent les th\u00e8mes privil\u00e9gi\u00e9s du dossier de notre premier num\u00e9ro.<br>\r\n<\/br>\r\n<strong>ISSN : 1911-4176<\/strong><br>\r\n<\/br>\r\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2025\/01\/Vol.-1-complet.pdf\">Pour t\u00e9l\u00e9charger le num\u00e9ro complet en PDF, cliquez ici<\/a><\/p><\/div><\/div><\/div>\n\n\n<p class=\"wp-block-tag-cloud\"><a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/metoo\/\" class=\"tag-cloud-link tag-link-101 tag-link-position-1\" style=\"font-size: 9.5135135135135pt;\" aria-label=\"#metoo (3 \u00e9l\u00e9ments)\">#metoo<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/analyse-litteraire\/\" class=\"tag-cloud-link tag-link-114 tag-link-position-2\" style=\"font-size: 13.927927927928pt;\" aria-label=\"analyse litt\u00e9raire (8 \u00e9l\u00e9ments)\">analyse litt\u00e9raire<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/anticapitalisme\/\" class=\"tag-cloud-link tag-link-263 tag-link-position-3\" style=\"font-size: 8pt;\" aria-label=\"anticapitalisme (2 \u00e9l\u00e9ments)\">anticapitalisme<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/article-theorique\/\" class=\"tag-cloud-link tag-link-162 tag-link-position-4\" style=\"font-size: 19.099099099099pt;\" aria-label=\"article th\u00e9orique (22 \u00e9l\u00e9ments)\">article th\u00e9orique<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/arts\/\" class=\"tag-cloud-link tag-link-214 tag-link-position-5\" style=\"font-size: 9.5135135135135pt;\" aria-label=\"arts (3 \u00e9l\u00e9ments)\">arts<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/art-visuel\/\" class=\"tag-cloud-link tag-link-155 tag-link-position-6\" style=\"font-size: 19.603603603604pt;\" aria-label=\"art visuel (24 \u00e9l\u00e9ments)\">art visuel<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/bande-dessinee\/\" class=\"tag-cloud-link tag-link-269 tag-link-position-7\" style=\"font-size: 8pt;\" aria-label=\"bande dessin\u00e9e (2 \u00e9l\u00e9ments)\">bande dessin\u00e9e<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/biopouvoir\/\" class=\"tag-cloud-link tag-link-186 tag-link-position-8\" style=\"font-size: 8pt;\" aria-label=\"biopouvoir \/ biopolitique (2 \u00e9l\u00e9ments)\">biopouvoir \/ biopolitique<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/controle-et-resistances-du-corps\/\" class=\"tag-cloud-link tag-link-183 tag-link-position-9\" style=\"font-size: 11.783783783784pt;\" aria-label=\"contr\u00f4le et r\u00e9sistances du corps (5 \u00e9l\u00e9ments)\">contr\u00f4le et r\u00e9sistances du corps<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/corps-et-corporalite\/\" class=\"tag-cloud-link tag-link-158 tag-link-position-10\" style=\"font-size: 15.063063063063pt;\" aria-label=\"corps et corporalit\u00e9 (10 \u00e9l\u00e9ments)\">corps et corporalit\u00e9<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/crise-climatique\/\" class=\"tag-cloud-link tag-link-171 tag-link-position-11\" style=\"font-size: 9.5135135135135pt;\" aria-label=\"crise climatique (3 \u00e9l\u00e9ments)\">crise climatique<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/creation-litteraire\/\" class=\"tag-cloud-link tag-link-247 tag-link-position-12\" style=\"font-size: 22pt;\" aria-label=\"cr\u00e9ation litt\u00e9raire (38 \u00e9l\u00e9ments)\">cr\u00e9ation litt\u00e9raire<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/diversite-corporelle\/\" class=\"tag-cloud-link tag-link-163 tag-link-position-13\" style=\"font-size: 10.774774774775pt;\" aria-label=\"diversit\u00e9 corporelle (4 \u00e9l\u00e9ments)\">diversit\u00e9 corporelle<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/foret\/\" class=\"tag-cloud-link tag-link-122 tag-link-position-14\" style=\"font-size: 9.5135135135135pt;\" aria-label=\"for\u00eat (3 \u00e9l\u00e9ments)\">for\u00eat<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/histoire\/\" class=\"tag-cloud-link tag-link-127 tag-link-position-15\" style=\"font-size: 12.666666666667pt;\" aria-label=\"histoire (6 \u00e9l\u00e9ments)\">histoire<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/identite\/\" class=\"tag-cloud-link tag-link-256 tag-link-position-16\" style=\"font-size: 12.666666666667pt;\" aria-label=\"identit\u00e9 (6 \u00e9l\u00e9ments)\">identit\u00e9<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/illustrations\/\" class=\"tag-cloud-link tag-link-147 tag-link-position-17\" style=\"font-size: 18.342342342342pt;\" aria-label=\"illustrations (19 \u00e9l\u00e9ments)\">illustrations<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/independance\/\" class=\"tag-cloud-link tag-link-257 tag-link-position-18\" style=\"font-size: 9.5135135135135pt;\" aria-label=\"ind\u00e9pendance (3 \u00e9l\u00e9ments)\">ind\u00e9pendance<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/intersectionnalite\/\" class=\"tag-cloud-link tag-link-165 tag-link-position-19\" style=\"font-size: 13.297297297297pt;\" aria-label=\"intersectionnalit\u00e9 (7 \u00e9l\u00e9ments)\">intersectionnalit\u00e9<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/invisibilisation-des-femmes\/\" class=\"tag-cloud-link tag-link-154 tag-link-position-20\" style=\"font-size: 10.774774774775pt;\" aria-label=\"invisibilisation des femmes (4 \u00e9l\u00e9ments)\">invisibilisation des femmes<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/luttes\/\" class=\"tag-cloud-link tag-link-137 tag-link-position-21\" style=\"font-size: 14.558558558559pt;\" aria-label=\"luttes (9 \u00e9l\u00e9ments)\">luttes<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/maternite\/\" class=\"tag-cloud-link tag-link-289 tag-link-position-22\" style=\"font-size: 9.5135135135135pt;\" aria-label=\"maternit\u00e9 (3 \u00e9l\u00e9ments)\">maternit\u00e9<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/militance\/\" class=\"tag-cloud-link tag-link-106 tag-link-position-23\" style=\"font-size: 14.558558558559pt;\" aria-label=\"militance (9 \u00e9l\u00e9ments)\">militance<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/mythes\/\" class=\"tag-cloud-link tag-link-192 tag-link-position-24\" style=\"font-size: 9.5135135135135pt;\" aria-label=\"mythes (3 \u00e9l\u00e9ments)\">mythes<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/nature\/\" class=\"tag-cloud-link tag-link-124 tag-link-position-25\" style=\"font-size: 10.774774774775pt;\" aria-label=\"nature (4 \u00e9l\u00e9ments)\">nature<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/non-binarite\/\" class=\"tag-cloud-link tag-link-554 tag-link-position-26\" style=\"font-size: 9.5135135135135pt;\" aria-label=\"non-binarit\u00e9 (3 \u00e9l\u00e9ments)\">non-binarit\u00e9<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/nouvelle\/\" class=\"tag-cloud-link tag-link-319 tag-link-position-27\" style=\"font-size: 10.774774774775pt;\" aria-label=\"nouvelle (4 \u00e9l\u00e9ments)\">nouvelle<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/photographie\/\" class=\"tag-cloud-link tag-link-102 tag-link-position-28\" style=\"font-size: 13.927927927928pt;\" aria-label=\"photographie (8 \u00e9l\u00e9ments)\">photographie<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/poesie\/\" class=\"tag-cloud-link tag-link-108 tag-link-position-29\" style=\"font-size: 19.351351351351pt;\" aria-label=\"po\u00e9sie (23 \u00e9l\u00e9ments)\">po\u00e9sie<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/quebec\/\" class=\"tag-cloud-link tag-link-152 tag-link-position-30\" style=\"font-size: 9.5135135135135pt;\" aria-label=\"Qu\u00e9bec (3 \u00e9l\u00e9ments)\">Qu\u00e9bec<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/reappropriation\/\" class=\"tag-cloud-link tag-link-113 tag-link-position-31\" style=\"font-size: 15.567567567568pt;\" aria-label=\"r\u00e9appropriation (11 \u00e9l\u00e9ments)\">r\u00e9appropriation<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/reflexion-et-essai\/\" class=\"tag-cloud-link tag-link-194 tag-link-position-32\" style=\"font-size: 15.063063063063pt;\" aria-label=\"r\u00e9flexion et essai (10 \u00e9l\u00e9ments)\">r\u00e9flexion et essai<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/sante\/\" class=\"tag-cloud-link tag-link-315 tag-link-position-33\" style=\"font-size: 10.774774774775pt;\" aria-label=\"sant\u00e9 (4 \u00e9l\u00e9ments)\">sant\u00e9<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/solidarite\/\" class=\"tag-cloud-link tag-link-100 tag-link-position-34\" style=\"font-size: 9.5135135135135pt;\" aria-label=\"solidarit\u00e9 (3 \u00e9l\u00e9ments)\">solidarit\u00e9<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/sorcieres-et-sorcellerie\/\" class=\"tag-cloud-link tag-link-131 tag-link-position-35\" style=\"font-size: 10.774774774775pt;\" aria-label=\"sorci\u00e8res et sorcellerie (4 \u00e9l\u00e9ments)\">sorci\u00e8res et sorcellerie<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/souffrances\/\" class=\"tag-cloud-link tag-link-279 tag-link-position-36\" style=\"font-size: 8pt;\" aria-label=\"souffrances (2 \u00e9l\u00e9ments)\">souffrances<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/temoignage\/\" class=\"tag-cloud-link tag-link-187 tag-link-position-37\" style=\"font-size: 17.081081081081pt;\" aria-label=\"t\u00e9moignage (15 \u00e9l\u00e9ments)\">t\u00e9moignage<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/violences\/\" class=\"tag-cloud-link tag-link-252 tag-link-position-38\" style=\"font-size: 15.567567567568pt;\" aria-label=\"violences (11 \u00e9l\u00e9ments)\">violences<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/violences-obstetricales-et-medicales\/\" class=\"tag-cloud-link tag-link-288 tag-link-position-39\" style=\"font-size: 8pt;\" aria-label=\"violences obst\u00e9tricales et m\u00e9dicales (2 \u00e9l\u00e9ments)\">violences obst\u00e9tricales et m\u00e9dicales<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/violences-sexuelles\/\" class=\"tag-cloud-link tag-link-184 tag-link-position-40\" style=\"font-size: 14.558558558559pt;\" aria-label=\"violences sexuelles (9 \u00e9l\u00e9ments)\">violences sexuelles<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/voix-resistantes\/\" class=\"tag-cloud-link tag-link-99 tag-link-position-41\" style=\"font-size: 15.063063063063pt;\" aria-label=\"voix r\u00e9sistantes (10 \u00e9l\u00e9ments)\">voix r\u00e9sistantes<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/ecoanxiete\/\" class=\"tag-cloud-link tag-link-168 tag-link-position-42\" style=\"font-size: 9.5135135135135pt;\" aria-label=\"\u00e9coanxi\u00e9t\u00e9 (3 \u00e9l\u00e9ments)\">\u00e9coanxi\u00e9t\u00e9<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/ecofeminisme\/\" class=\"tag-cloud-link tag-link-119 tag-link-position-43\" style=\"font-size: 10.774774774775pt;\" aria-label=\"\u00e9cof\u00e9minisme (4 \u00e9l\u00e9ments)\">\u00e9cof\u00e9minisme<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/ecriture-inclusive\/\" class=\"tag-cloud-link tag-link-552 tag-link-position-44\" style=\"font-size: 10.774774774775pt;\" aria-label=\"\u00e9criture inclusive (4 \u00e9l\u00e9ments)\">\u00e9criture inclusive<\/a>\n<a href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/tag\/emancipation-des-femmes\/\" class=\"tag-cloud-link tag-link-298 tag-link-position-45\" style=\"font-size: 8pt;\" aria-label=\"\u00e9mancipation des femmes (2 \u00e9l\u00e9ments)\">\u00e9mancipation des femmes<\/a><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":28,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[],"class_list":["post-32","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives | Revue F\u00e9min\u00c9tudes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros-revue\/archives\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives | Revue F\u00e9min\u00c9tudes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros-revue\/archives\/\" \/>\n<meta property=\"og:site_name\" content=\"Revue F\u00e9min\u00c9tudes\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-14T21:21:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/04\/Logo-carre-NONOFFICIEL.png\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/revues-alpha.uqam.ca\\\/feminetudes\\\/numeros-revue\\\/archives\\\/\",\"url\":\"https:\\\/\\\/revues-alpha.uqam.ca\\\/feminetudes\\\/numeros-revue\\\/archives\\\/\",\"name\":\"Archives | Revue F\u00e9min\u00c9tudes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revues-alpha.uqam.ca\\\/feminetudes\\\/#website\"},\"datePublished\":\"2023-01-10T21:21:04+00:00\",\"dateModified\":\"2024-08-14T21:21:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/revues-alpha.uqam.ca\\\/feminetudes\\\/numeros-revue\\\/archives\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/revues-alpha.uqam.ca\\\/feminetudes\\\/numeros-revue\\\/archives\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/revues-alpha.uqam.ca\\\/feminetudes\\\/numeros-revue\\\/archives\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"UQAM\",\"item\":\"https:\\\/\\\/uqam.ca\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revue F\u00e9min\u00c9tudes\",\"item\":\"https:\\\/\\\/revues-alpha.uqam.ca\\\/feminetudes\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Num\u00e9ros\",\"item\":\"https:\\\/\\\/revues-alpha.uqam.ca\\\/feminetudes\\\/numeros-revue\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Archives\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/revues-alpha.uqam.ca\\\/feminetudes\\\/#website\",\"url\":\"https:\\\/\\\/revues-alpha.uqam.ca\\\/feminetudes\\\/\",\"name\":\"Mod\u00e8le revue\",\"description\":\"\",\"alternateName\":\"Mod\u00e8le revue UQAM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/revues-alpha.uqam.ca\\\/feminetudes\\\/recherche\\\/?q={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives | Revue F\u00e9min\u00c9tudes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros-revue\/archives\/","og_locale":"fr_CA","og_type":"article","og_title":"Archives | Revue F\u00e9min\u00c9tudes","og_url":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros-revue\/archives\/","og_site_name":"Revue F\u00e9min\u00c9tudes","article_modified_time":"2024-08-14T21:21:36+00:00","og_image":[{"width":360,"height":360,"url":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-content\/uploads\/sites\/8\/2024\/04\/Logo-carre-NONOFFICIEL.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros-revue\/archives\/","url":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros-revue\/archives\/","name":"Archives | Revue F\u00e9min\u00c9tudes","isPartOf":{"@id":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/#website"},"datePublished":"2023-01-10T21:21:04+00:00","dateModified":"2024-08-14T21:21:36+00:00","breadcrumb":{"@id":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros-revue\/archives\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros-revue\/archives\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros-revue\/archives\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"UQAM","item":"https:\/\/uqam.ca"},{"@type":"ListItem","position":2,"name":"Revue F\u00e9min\u00c9tudes","item":"https:\/\/revues-alpha.uqam.ca\/feminetudes"},{"@type":"ListItem","position":3,"name":"Num\u00e9ros","item":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/numeros-revue\/"},{"@type":"ListItem","position":4,"name":"Archives"}]},{"@type":"WebSite","@id":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/#website","url":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/","name":"Mod\u00e8le revue","description":"","alternateName":"Mod\u00e8le revue UQAM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/recherche\/?q={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"coauthors":[{"link":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/laporte_jon\/","display_name":"Jonathan Laporte"}],"author_meta":{"author_link":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/author\/laporte_jon\/","display_name":"Jonathan Laporte"},"relative_dates":{"created":"Posted 3 ann\u00e9es ago","modified":"Updated 2 ann\u00e9es ago"},"absolute_dates":{"created":"Posted on 2023-01-10","modified":"Updated on 2024-08-14"},"absolute_dates_time":{"created":"Posted on 2023-01-10 16 h 21 min","modified":"Updated on 2024-08-14 21 h 21 min"},"featured_img_caption":"","featured_img":false,"series_order":"","_links":{"self":[{"href":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-json\/wp\/v2\/pages\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-json\/wp\/v2\/comments?post=32"}],"version-history":[{"count":5,"href":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-json\/wp\/v2\/pages\/32\/revisions"}],"predecessor-version":[{"id":14817,"href":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-json\/wp\/v2\/pages\/32\/revisions\/14817"}],"up":[{"embeddable":true,"href":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-json\/wp\/v2\/pages\/28"}],"wp:attachment":[{"href":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-json\/wp\/v2\/media?parent=32"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revues-alpha.uqam.ca\/feminetudes\/wp-json\/wp\/v2\/categories?post=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}